{"id":10507,"date":"2019-10-02T08:15:10","date_gmt":"2019-10-02T11:15:10","guid":{"rendered":"https:\/\/cipe.org.br\/novo\/?p=10507"},"modified":"2019-10-04T08:22:23","modified_gmt":"2019-10-04T11:22:23","slug":"cipe-participa-da-normatizacao-dos-procedimentos-roboticos","status":"publish","type":"post","link":"https:\/\/cipe.org.br\/novo\/cipe-participa-da-normatizacao-dos-procedimentos-roboticos\/","title":{"rendered":"CIPE participa da normatiza\u00e7\u00e3o dos procedimentos rob\u00f3ticos"},"content":{"rendered":"<p>No dia 24 de setembro, representando a Dra. Maria do Socorro Mendon\u00e7a de Campos, presidente da CIPE, o Dr. Edward Esteves Pereira, coordenador da Comiss\u00e3o de Videocirurgia da CIPE, participou da reuni\u00e3o do Conselho Federal de Medicina (CFM) sobre a normatiza\u00e7\u00e3o do uso de instrumentos rob\u00f3ticos em procedimentos cir\u00fargicos em geral. Desde sua cria\u00e7\u00e3o, em agosto de 2019, o Dr. Edward j\u00e1 participa, pela CIPE, da Comiss\u00e3o Nacional de V\u00eddeocirurgia Rob\u00f4-assistida da Associa\u00e7\u00e3o M\u00e9dica Brasileira (AMB), que tem por objetivo definir os aspectos legais, \u00e9ticos, econ\u00f4micos e tecnol\u00f3gicos relacionados ao tema. Tamb\u00e9m algumas especialidades j\u00e1 organizam grupos de trabalho para analisar o assunto no \u00e2mbito de suas compet\u00eancias.<\/p>\n<p>\u201cAntes j\u00e1 t\u00ednhamos a Sociedade Brasileira de Cirurgia Laparosc\u00f3pica (Sobracil), com membros de v\u00e1rias especialidades atuando em v\u00eddeocirurgia, por\u00e9m n\u00e3o representava nenhuma, apesar de registrada na AMB. Assim, a AMB criou uma comiss\u00e3o conjunta, tendo em vista que a nova ferramenta \u2013 a rob\u00f3tica \u2013 seria equivalente ao que ocorreu com a entrada da v\u00eddeocirurgia, por\u00e9m, com uma grande diferen\u00e7a: a intera\u00e7\u00e3o indireta m\u00e9dico-paciente e j\u00e1 com implica\u00e7\u00f5es legais aqui em outros pa\u00edses que utilizam rob\u00f3tica desde 2000. O objetivo \u00e9 a normatiza\u00e7\u00e3o da cirurgia rob\u00f3tica no Brasil, juntando todas as especialidades que j\u00e1 fazem cirurgia por v\u00eddeo, como a nossa, e convidou os representantes de todas essas associa\u00e7\u00f5es para, j\u00e1 na primeira reuni\u00e3o, de agosto, discutir o credenciamento dos cirurgi\u00f5es, as indica\u00e7\u00f5es e os aspectos legais, \u00e9ticos, econ\u00f4micos, e tecnol\u00f3gicos, ligados ao aparecimento de novos equipamentos\u201d, disse o representante da Cirurgia Pedi\u00e1trica na comiss\u00e3o da AMB.<\/p>\n<p>Segundo ele, no Brasil essa regulamenta\u00e7\u00e3o apresenta certa urg\u00eancia, uma vez que j\u00e1 h\u00e1 62 equipamentos rob\u00f3ticos daVinci em uso no Brasil, mas n\u00e3o h\u00e1 regulamenta\u00e7\u00e3o de pr\u00e9-requisitos ou treinamento pr\u00e9vio que habilite os cirurgi\u00f5es para utilizar adequadamente essa ferramenta, e novos tipos de rob\u00f4s v\u00e3o necessitar outra capacita\u00e7\u00e3o e credenciamento. Outro motivo \u00e9 a falta de par\u00e2metros para definir responsabilidades \u2013 seja do cirurgi\u00e3o que manipula os instrumentos rob\u00f3ticos \u00e0 dist\u00e2ncia, seja da equipe cir\u00fargica que assiste diretamente o paciente no centro cir\u00fargico (backside) durante o procedimento \u2013 em caso de intercorr\u00eancia ou quebra de rela\u00e7\u00e3o m\u00e9dico-paciente.<\/p>\n<p>O Dr. Edward, especialista em V\u00eddeocirurgia Pedi\u00e1trica e que, ap\u00f3s treinamentos em Bogot\u00e1 (Col\u00f4mbia) \u2013 quando estes apenas come\u00e7avam no Brasil \u2013, vem estimulando a realiza\u00e7\u00e3o v\u00eddeocirurgias rob\u00f4-assistidas e projetando instrumentos de tamanho reduzido para crian\u00e7as pequenas, comenta que, por causa do termo empregado, leigos imaginam, erroneamente, que essas cirurgias, que creem mais seguras, sejam feitas por rob\u00f4s aut\u00f4nomos, inteligentes. \u201cNa verdade, h\u00e1 um cirurgi\u00e3o comandando os instrumentos \u00e0 dist\u00e2ncia, como se fosse um joystick, um videogame, junto ou longe da sala cir\u00fargica, visualizando o procedimento em 3D por visor ocular ou monitor (console), enquanto outro cirurgi\u00e3o e sua equipe permanecem com o paciente, realizando seu monitoramento e auxiliando na opera\u00e7\u00e3o com os furos na parede, introdu\u00e7\u00f5es e trocas de instrumentos, limpezas, fios, s\u00edntese final\u201d, esclarece.<\/p>\n<p>E essa vis\u00e3o distorcida pela sociedade, associada a eventual descontentamento de pacientes e familiares com os resultados, tem acarretado a abertura de processos contra cirurgi\u00f5es e equipes nos conselhos de Medicina, os quais permanecem travados em virtude de aus\u00eancia de legisla\u00e7\u00e3o que possa embasar julgamentos.<\/p>\n<p><strong>APLICA\u00c7\u00d5ES<\/strong><\/p>\n<p>A seu ver, o uso de instrumentos rob\u00f3ticos se justifica em cirurgias mais complexas, dif\u00edceis de realizar com as pin\u00e7as retas, tradicionais, usadas em v\u00eddeocirurgias: \u201cAs pin\u00e7as rob\u00f3ticas s\u00e3o mais precisas, pois s\u00e3o mais articuladas e fazem movimentos de at\u00e9 360 graus, algo que nossa m\u00e3o n\u00e3o consegue fazer; a c\u00e2mera rob\u00f3tica tamb\u00e9m pode ser flex\u00edvel, similar a um endosc\u00f3pio. Ent\u00e3o, com essas ferramentas podemos fazer cirurgias mais precisas, mais delicadas em espa\u00e7os pequenos, ideais em crian\u00e7as, caso tenhamos di\u00e2metros de instrumentos mais finos que os 8 a 12 mm atuais. Com as pin\u00e7as grandes atuais, a rob\u00f3tica n\u00e3o tem vantagens em muitos casos neonatais ou de lactentes\u201d.<\/p>\n<p>Outra indica\u00e7\u00e3o \u00e9 o fato de permitir, desde que haja equipamentos, a realiza\u00e7\u00e3o de cirurgias \u00e0 dist\u00e2ncia, remotamente, como em \u00e1reas de guerra, em pa\u00edses mais pobres, n\u00e3o havendo in loco um especialista para realizar determinado procedimento, ou at\u00e9, mais al\u00e9m, em viagens espaciais.<\/p>\n<p>O Dr. Edward ressalta que a chamada v\u00eddeocirurgia rob\u00f4-assistida \u00e9 mais cara e n\u00e3o tem seu custo coberto por conv\u00eanios; se o paciente optar por essa modalidade, ter\u00e1 um custo adicional de at\u00e9 R$ 15 mil, a t\u00edtulo de complementa\u00e7\u00e3o do tratamento, a ser pago por fora, pois os custos dos equipamentos e de sua manuten\u00e7\u00e3o s\u00e3o hoje ainda bastante elevados.<\/p>\n<p>No CFM, ele participar\u00e1 do grupo de estudo e normatiza\u00e7\u00e3o da cirurgia rob\u00f3tica dentro da C\u00e2mara T\u00e9cnica de Cirurgia Geral, representando a CIPE. Na primeira reuni\u00e3o, em setembro, informou as necessidades da especialidade, as in\u00fameras aplica\u00e7\u00f5es em Pediatria, salientando que as crian\u00e7as devem ser operadas por cirurgi\u00f5es pedi\u00e1tricos e\/ou urologistas especializados em cirurgias urol\u00f3gicas de crian\u00e7as e destacou a import\u00e2ncia da valoriza\u00e7\u00e3o do T\u00edtulo de Especialista ou, ao menos, dos membros associados \u00e0s sociedades das especialidades. Ali est\u00e3o cientes que a estrutura se iniciou nas cl\u00ednicas privadas, faltando ainda a capacita\u00e7\u00e3o em servi\u00e7os p\u00fablicos e universit\u00e1rios, tal como ocorreu no princ\u00edpio da V\u00eddeocirurgia. O grupo acredita que os equipamentos ser\u00e3o barateados com o tempo e o aumento da utiliza\u00e7\u00e3o, o que elevar\u00e1 as demandas \u00e9ticas e jur\u00eddicas, para m\u00e9dicos e hospitais. Atualmente a maioria dos 62 consoles est\u00e1 em S\u00e3o Paulo, informa.<\/p>\n<p><strong>PAR\u00c2METROS<\/strong><\/p>\n<p>Para o grupo, o trabalho de normatiza\u00e7\u00e3o deve envolver a exig\u00eancia de treinamento espec\u00edfico dos cirurgi\u00f5es de acordo com equipamento\/marca que ir\u00e1 utilizar, pois a pr\u00e1tica \u00f3culo-motora e limita\u00e7\u00e3o t\u00e1til s\u00e3o diferentes da da v\u00eddeocirurgia padr\u00e3o, e a tecnologia nesse campo est\u00e1 avan\u00e7ando rapidamente. Tamb\u00e9m dever\u00e1 definir o especialista a realizar cada tipo de cirurgia \u2013 j\u00e1 que, h\u00e1 intersec\u00e7\u00f5es de especialidades, como no caso das cirurgias oncol\u00f3gicas, urol\u00f3gicas, ginecol\u00f3gicas e tor\u00e1cicas com a Cirurgia Pedi\u00e1trica \u2013 e distribuir as responsabilidades de cada procedimento entre todos os envolvidos.<\/p>\n<p>\u201cV\u00e1rios pa\u00edses j\u00e1 regulamentaram a Cirurgia Rob\u00f3tica, ent\u00e3o, nosso trabalho n\u00e3o parte do zero\u201d, avalia. O Dr. Edward sugeriu ao conselho de Medicina que fossem analisadas as regulamenta\u00e7\u00f5es de pa\u00edses como Estados Unidos, Fran\u00e7a, It\u00e1lia, Alemanha, Inglaterra, Canad\u00e1 e Jap\u00e3o, argumentando, entretanto, que esses modelos dever\u00e3o ser adequados ao Brasil.<\/p>\n<p>O Cremerj e a C\u00e2mara T\u00e9cnica do CFM j\u00e1 sugeriram e redigiram um projeto de base para regulamenta\u00e7\u00e3o de aplica\u00e7\u00e3o brasileira, e estar\u00e3o sendo analisados para complementa\u00e7\u00e3o, ajustes, com ganho de tempo.<\/p>\n<p>Ele prev\u00ea que a regulamenta\u00e7\u00e3o deva estar conclu\u00edda at\u00e9 o final deste ano e prognostica: \u201cA Cirurgia Rob\u00f3tica j\u00e1 est\u00e1 se tornando mais barata; ela chegou, para valer, e, assim que sua institui\u00e7\u00e3o adquirir um rob\u00f4, recomenda-se o treinamento para dar mais oportunidades a casos onde seu uso seria bem indicado.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 24 de setembro, representando a Dra. Maria do Socorro Mendon\u00e7a de Campos, presidente da CIPE, o Dr. Edward Esteves Pereira, coordenador da Comiss\u00e3o de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":10509,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"_links":{"self":[{"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/posts\/10507"}],"collection":[{"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/comments?post=10507"}],"version-history":[{"count":2,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/posts\/10507\/revisions"}],"predecessor-version":[{"id":10523,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/posts\/10507\/revisions\/10523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/media\/10509"}],"wp:attachment":[{"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/media?parent=10507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/categories?post=10507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cipe.org.br\/novo\/wp-json\/wp\/v2\/tags?post=10507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}